{"id":88588,"date":"2025-09-02T14:54:53","date_gmt":"2025-09-02T07:54:53","guid":{"rendered":"https:\/\/thisav.me\/eu-disse-para-voce-parar\/"},"modified":"2025-09-02T14:54:53","modified_gmt":"2025-09-02T07:54:53","slug":"eu-disse-para-voce-parar","status":"publish","type":"post","link":"https:\/\/supjav.video\/pt-br\/eu-disse-para-voce-parar\/","title":{"rendered":"Eu disse para voc\u00ea parar."},"content":{"rendered":"<p>Eu disse para voc\u00ea parar. Sinopse A linda garota acabou de namorar o namorado e ele ainda n\u00e3o est\u00e1 junto. At\u00e9 que ela estava de mau humor e se masturbou atrav\u00e9s da c\u00e2mera para mostrar ao namorado, mas naquela \u00e9poca, seu meio-irm\u00e3o veio ver e sentiu muita pena de sua irm\u00e3 e se ofereceu para ajudar a aliviar seu sofrimento. Estrelado por Miuzxc<br \/>\n<iframe loading=\"lazy\" class=\"videowrapper\" src=\"https:\/\/fembeqv2.xyz\/player\/index.php?data=0141a8aedb1b53970fac7c81dac79fbe\" width=\"300\" height=\"175\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eu disse para voc\u00ea parar. Sinopse A linda garota acabou de namorar o namorado e ele ainda n\u00e3o est\u00e1 junto. At\u00e9 que ela estava de mau humor e se masturbou atrav\u00e9s da c\u00e2mera para mostrar ao namorado, mas naquela \u00e9poca, seu meio-irm\u00e3o veio ver e sentiu muita pena de sua irm\u00e3 e se ofereceu para [&#8230;]<\/p>\n<p><a class=\"btn btn-primary wpst-read-more-link\" href=\"https:\/\/supjav.video\/pt-br\/eu-disse-para-voce-parar\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":88568,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[279,394,1730,115],"tags":[1082,224,17090,13524,1172,1670,2340],"actors":[13525],"class_list":["post-88588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-av-ntr-pt-br","category-novo-av","category-pornografia-asiatica","category-vazamento-sem-censura","tag-bonito","tag-gozar-dentro","tag-irmao-pt-br-2","tag-menina-vietnamita","tag-pornhuber-pt-br","tag-pose-de-cao","tag-sub-tailandes","actors-miuzxc-pt-br"],"_links":{"self":[{"href":"https:\/\/supjav.video\/pt-br\/wp-json\/wp\/v2\/posts\/88588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/supjav.video\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/supjav.video\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/supjav.video\/pt-br\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/supjav.video\/pt-br\/wp-json\/wp\/v2\/comments?post=88588"}],"version-history":[{"count":0,"href":"https:\/\/supjav.video\/pt-br\/wp-json\/wp\/v2\/posts\/88588\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/supjav.video\/pt-br\/wp-json\/wp\/v2\/media\/88568"}],"wp:attachment":[{"href":"https:\/\/supjav.video\/pt-br\/wp-json\/wp\/v2\/media?parent=88588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/supjav.video\/pt-br\/wp-json\/wp\/v2\/categories?post=88588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/supjav.video\/pt-br\/wp-json\/wp\/v2\/tags?post=88588"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/supjav.video\/pt-br\/wp-json\/wp\/v2\/actors?post=88588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}